{"id":12774,"count":1,"description":"","link":"https:\/\/allgujaratnews.in\/en\/tag\/%e0%aa%b5%e0%aa%bf%e0%aa%b6%e0%ab%8d%e0%aa%b5%e0%aa%ae%e0%aa%be%e0%aa%82-%e0%aa%ae%e0%ab%8b%e0%aa%a6%e0%ab%80%e0%aa%a8%e0%ab%80-%e0%aa%ab%e0%aa%9c%e0%ab%87%e0%aa%a4%e0%ab%80\/","name":"\u0ab5\u0abf\u0ab6\u0acd\u0ab5\u0aae\u0abe\u0a82 \u0aae\u0acb\u0aa6\u0ac0\u0aa8\u0ac0 \u0aab\u0a9c\u0ac7\u0aa4\u0ac0","slug":"%e0%aa%b5%e0%aa%bf%e0%aa%b6%e0%ab%8d%e0%aa%b5%e0%aa%ae%e0%aa%be%e0%aa%82-%e0%aa%ae%e0%ab%8b%e0%aa%a6%e0%ab%80%e0%aa%a8%e0%ab%80-%e0%aa%ab%e0%aa%9c%e0%ab%87%e0%aa%a4%e0%ab%80","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/allgujaratnews.in\/en\/wp-json\/wp\/v2\/tags\/12774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allgujaratnews.in\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/allgujaratnews.in\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/allgujaratnews.in\/en\/wp-json\/wp\/v2\/posts?tags=12774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}