{"id":6043,"count":1,"description":"","link":"https:\/\/allgujaratnews.in\/gj\/tag\/%e0%aa%b8%e0%aa%be%e0%aa%ac%e0%aa%b0%e0%aa%ae%e0%aa%a4%e0%ab%80%e0%aa%ae%e0%aa%be%e0%aa%82-%e0%aa%85%e0%aa%95%e0%ab%8d%e0%aa%b7%e0%aa%b0-%e0%ab%a7%e0%ab%a7%e0%ab%a7\/","name":"\u0ab8\u0abe\u0aac\u0ab0\u0aae\u0aa4\u0ac0\u0aae\u0abe\u0a82 \u0a85\u0a95\u0acd\u0ab7\u0ab0-\u0ae7\u0ae7\u0ae7","slug":"%e0%aa%b8%e0%aa%be%e0%aa%ac%e0%aa%b0%e0%aa%ae%e0%aa%a4%e0%ab%80%e0%aa%ae%e0%aa%be%e0%aa%82-%e0%aa%85%e0%aa%95%e0%ab%8d%e0%aa%b7%e0%aa%b0-%e0%ab%a7%e0%ab%a7%e0%ab%a7","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/allgujaratnews.in\/gj\/wp-json\/wp\/v2\/tags\/6043"}],"collection":[{"href":"https:\/\/allgujaratnews.in\/gj\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/allgujaratnews.in\/gj\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/allgujaratnews.in\/gj\/wp-json\/wp\/v2\/posts?tags=6043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}