{"id":6050,"count":1,"description":"","link":"https:\/\/allgujaratnews.in\/gj\/tag\/%e0%aa%b8%e0%ab%8d%e0%aa%9f%e0%ab%87%e0%aa%a1%e0%ab%80%e0%aa%af%e0%aa%ae%e0%aa%ae%e0%aa%be%e0%aa%82-%e0%aa%b9%e0%ab%80%e0%aa%b0%e0%ab%8b-%e0%aa%b9%e0%ab%8b%e0%aa%a8%e0%ab%8d%e0%aa%a1%e0%aa%be\/","name":"\u0ab8\u0acd\u0a9f\u0ac7\u0aa1\u0ac0\u0aaf\u0aae\u0aae\u0abe\u0a82 \u0ab9\u0ac0\u0ab0\u0acb \u0ab9\u0acb\u0aa8\u0acd\u0aa1\u0abe","slug":"%e0%aa%b8%e0%ab%8d%e0%aa%9f%e0%ab%87%e0%aa%a1%e0%ab%80%e0%aa%af%e0%aa%ae%e0%aa%ae%e0%aa%be%e0%aa%82-%e0%aa%b9%e0%ab%80%e0%aa%b0%e0%ab%8b-%e0%aa%b9%e0%ab%8b%e0%aa%a8%e0%ab%8d%e0%aa%a1%e0%aa%be","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/allgujaratnews.in\/gj\/wp-json\/wp\/v2\/tags\/6050"}],"collection":[{"href":"https:\/\/allgujaratnews.in\/gj\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/allgujaratnews.in\/gj\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/allgujaratnews.in\/gj\/wp-json\/wp\/v2\/posts?tags=6050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}